{"id":6157,"date":"2023-12-29T20:43:36","date_gmt":"2023-12-29T23:43:36","guid":{"rendered":"https:\/\/autofans.com.ar\/?p=6157"},"modified":"2023-12-29T20:43:36","modified_gmt":"2023-12-29T23:43:36","slug":"toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate","status":"publish","type":"post","link":"https:\/\/autofans.com.ar\/index.php\/2023\/12\/29\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\/","title":{"rendered":"Toyota dos millones de unidades fabricadas en su planta de Z\u00e1rate"},"content":{"rendered":"<p>Toyota Argentina celebra un logro excepcional: la producci\u00f3n de dos millones de veh\u00edculos en su planta de Z\u00e1rate, marcando un hito significativo desde el inicio de sus operaciones en 1997. En apenas siete a\u00f1os, la compa\u00f1\u00eda duplic\u00f3 su producci\u00f3n desde el primer mill\u00f3n alcanzado en 2016. La pick-up Hilux se destaca como el modelo m\u00e1s fabricado en la historia de la industria automotriz argentina, con 1.679.096 unidades, mientras que el SUV SW4 contribuye con 320.904 veh\u00edculos producidos.<\/p>\n<p>&nbsp;<\/p>\n<h2>Un proyecto sustentable desde 1994<\/h2>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_6162\" aria-describedby=\"caption-attachment-6162\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-6162 size-full\" src=\"https:\/\/autofans.com.ar\/wp-content\/uploads\/2023\/12\/foto-6-1.jpg\" alt=\"Toyota\" width=\"1000\" height=\"667\" srcset=\"https:\/\/autofans.com.ar\/wp-content\/uploads\/2023\/12\/foto-6-1.jpg 1000w, https:\/\/autofans.com.ar\/wp-content\/uploads\/2023\/12\/foto-6-1-300x200.jpg 300w, https:\/\/autofans.com.ar\/wp-content\/uploads\/2023\/12\/foto-6-1-768x512.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-6162\" class=\"wp-caption-text\">Inicio de construcci\u00f3n de la planta de Z\u00e1rate<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Un Proyecto Sustentable de Largo Plazo Desde su decisi\u00f3n en 1994 de establecerse en Z\u00e1rate, Toyota ha consolidado su posici\u00f3n como actor clave en la industria automotriz argentina. La planta, inaugurada en 1997 como la primera de origen japon\u00e9s en el pa\u00eds, ha sido fundamental para la producci\u00f3n de la Hilux, que desde su lanzamiento ha sido la pick-up de una tonelada m\u00e1s vendida en Am\u00e9rica Latina. La planta, en constante crecimiento, emplea hoy a m\u00e1s de 8.500 personas y contribuye al trabajo de alrededor de 35.000 personas en su cadena de valor.<\/p>\n<p>&nbsp;<\/p>\n<h2>Toyota Hilux &#8211; calidad y liderazgo en 16 versiones \u00fanicas<\/h2>\n<p>Legado de Calidad y Expansi\u00f3n Continua La Hilux, reconocida por su calidad, durabilidad y confiabilidad, ha conquistado el coraz\u00f3n de miles de clientes en Argentina y la regi\u00f3n. Con un porfolio que abarca 16 versiones, diferentes configuraciones de cabina, transmisiones y tracci\u00f3n, la pick-up ha mantenido su posici\u00f3n l\u00edder. En 2023, Toyota present\u00f3 dos nuevas versiones: la cuarta generaci\u00f3n de Hilux GR-Sport, la variante deportiva, y la Hilux SRX, que incorpora mejoras para brindar un mayor confort de marcha.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-6158 size-full\" src=\"https:\/\/autofans.com.ar\/wp-content\/uploads\/2023\/12\/foto-4-11.jpg\" alt=\"Toyota\" width=\"1000\" height=\"667\" srcset=\"https:\/\/autofans.com.ar\/wp-content\/uploads\/2023\/12\/foto-4-11.jpg 1000w, https:\/\/autofans.com.ar\/wp-content\/uploads\/2023\/12\/foto-4-11-300x200.jpg 300w, https:\/\/autofans.com.ar\/wp-content\/uploads\/2023\/12\/foto-4-11-768x512.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Celebraci\u00f3n de un Hito Hist\u00f3rico El logro de dos millones de unidades producidas se celebr\u00f3 en la planta de Z\u00e1rate con la presencia de autoridades municipales, directivos de la compa\u00f1\u00eda, empleados, sindicatos, proveedores y concesionarios. El compromiso de Toyota con la calidad y la innovaci\u00f3n se refleja en este hito, respaldando su posici\u00f3n como l\u00edder en la industria automotriz argentina y dejando una huella significativa en la comunidad.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><i>Para enterarte de m\u00e1s novedades, no dejes de leer\u00a0<\/i><a href=\"https:\/\/autofans.thebrandsoup.com\/\"><i>nuestras notas<\/i><\/a><i>, de ver<\/i><b><i>\u00a0<\/i><\/b><a href=\"https:\/\/www.youtube.com\/channel\/UCgAC8UGHZYbT6P7PpmVnP7g\"><b><i>AUTOFANS TV<\/i><\/b><\/a><b><i>\u00a0<\/i><\/b><i>en nuestro\u00a0canal de Youtube. Adem\u00e1s seguinos en\u00a0<\/i><a href=\"https:\/\/www.instagram.com\/autofanstv\/\"><i>INSTAGRAM<\/i><\/a><i> y <\/i><a href=\"https:\/\/www.facebook.com\/autofansmas\/\"><i>FACEBOOK<\/i><\/a><i> para no perderte nada sobre las novedades del segmento automotor de Argentina y el mundo.<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toyota Argentina celebra un logro excepcional: la producci\u00f3n de dos millones de veh\u00edculos en su&#8230;<\/p>\n","protected":false},"author":2,"featured_media":6161,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,5],"tags":[3229,1020,278,86,886,279,3228,40,3227,51],"class_list":["post-6157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-otros","tag-dos-millones-de-unidades","tag-fabricacion-de-vehiculos","tag-hilux","tag-industria-automotriz","tag-innovacion-automotriz","tag-pick-up","tag-produccion-en-zarate","tag-suv","tag-sw4","tag-toyota-argentina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Toyota dos millones de unidades fabricadas en su planta de Z\u00e1rate -<\/title>\n<meta name=\"description\" content=\"Toyota celebra un logro excepcional: la producci\u00f3n de dos millones de veh\u00edculos en su planta de Z\u00e1rate, marcando un hito significativo...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/autofans.com.ar\/index.php\/2023\/12\/29\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Toyota dos millones de unidades fabricadas en su planta de Z\u00e1rate -\" \/>\n<meta property=\"og:description\" content=\"Toyota celebra un logro excepcional: la producci\u00f3n de dos millones de veh\u00edculos en su planta de Z\u00e1rate, marcando un hito significativo...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autofans.com.ar\/index.php\/2023\/12\/29\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-29T23:43:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/autofans.com.ar\/wp-content\/uploads\/2023\/12\/foto-1-19.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alejandro Gabriel Rosito\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alejandro Gabriel Rosito\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/autofans.com.ar\\\/index.php\\\/2023\\\/12\\\/29\\\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autofans.com.ar\\\/index.php\\\/2023\\\/12\\\/29\\\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\\\/\"},\"author\":{\"name\":\"Alejandro Gabriel Rosito\",\"@id\":\"https:\\\/\\\/autofans.com.ar\\\/#\\\/schema\\\/person\\\/4a8dda0b6df83ac3d6723e921274c2aa\"},\"headline\":\"Toyota dos millones de unidades fabricadas en su planta de Z\u00e1rate\",\"datePublished\":\"2023-12-29T23:43:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/autofans.com.ar\\\/index.php\\\/2023\\\/12\\\/29\\\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\\\/\"},\"wordCount\":432,\"image\":{\"@id\":\"https:\\\/\\\/autofans.com.ar\\\/index.php\\\/2023\\\/12\\\/29\\\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autofans.com.ar\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/foto-1-19.jpg\",\"keywords\":[\"Dos Millones de Unidades\",\"fabricaci\u00f3n de veh\u00edculos\",\"Hilux\",\"Industria Automotriz\",\"Innovaci\u00f3n automotriz\",\"Pick-up\",\"Producci\u00f3n en Z\u00e1rate\",\"SUV\",\"SW4\",\"Toyota Argentina\"],\"articleSection\":[\"NOTICIAS\",\"PICK UPs, UTILITARIOS Y OTROS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autofans.com.ar\\\/index.php\\\/2023\\\/12\\\/29\\\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\\\/\",\"url\":\"https:\\\/\\\/autofans.com.ar\\\/index.php\\\/2023\\\/12\\\/29\\\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\\\/\",\"name\":\"Toyota dos millones de unidades fabricadas en su planta de Z\u00e1rate -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autofans.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/autofans.com.ar\\\/index.php\\\/2023\\\/12\\\/29\\\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/autofans.com.ar\\\/index.php\\\/2023\\\/12\\\/29\\\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autofans.com.ar\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/foto-1-19.jpg\",\"datePublished\":\"2023-12-29T23:43:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/autofans.com.ar\\\/#\\\/schema\\\/person\\\/4a8dda0b6df83ac3d6723e921274c2aa\"},\"description\":\"Toyota celebra un logro excepcional: la producci\u00f3n de dos millones de veh\u00edculos en su planta de Z\u00e1rate, marcando un hito significativo...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autofans.com.ar\\\/index.php\\\/2023\\\/12\\\/29\\\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autofans.com.ar\\\/index.php\\\/2023\\\/12\\\/29\\\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/autofans.com.ar\\\/index.php\\\/2023\\\/12\\\/29\\\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/autofans.com.ar\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/foto-1-19.jpg\",\"contentUrl\":\"https:\\\/\\\/autofans.com.ar\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/foto-1-19.jpg\",\"width\":1000,\"height\":667,\"caption\":\"Toyota\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autofans.com.ar\\\/index.php\\\/2023\\\/12\\\/29\\\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/autofans.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Toyota dos millones de unidades fabricadas en su planta de Z\u00e1rate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autofans.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/autofans.com.ar\\\/\",\"name\":\"\",\"description\":\"El multimedio referente de la industria automotriz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autofans.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/autofans.com.ar\\\/#\\\/schema\\\/person\\\/4a8dda0b6df83ac3d6723e921274c2aa\",\"name\":\"Alejandro Gabriel Rosito\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16c5dda1489adfc62618084dcbb91cffd879c374b13fe5dd8e44ed6733852c88?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16c5dda1489adfc62618084dcbb91cffd879c374b13fe5dd8e44ed6733852c88?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16c5dda1489adfc62618084dcbb91cffd879c374b13fe5dd8e44ed6733852c88?s=96&d=mm&r=g\",\"caption\":\"Alejandro Gabriel Rosito\"},\"url\":\"https:\\\/\\\/autofans.com.ar\\\/index.php\\\/author\\\/gabrielr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Toyota dos millones de unidades fabricadas en su planta de Z\u00e1rate -","description":"Toyota celebra un logro excepcional: la producci\u00f3n de dos millones de veh\u00edculos en su planta de Z\u00e1rate, marcando un hito significativo...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/autofans.com.ar\/index.php\/2023\/12\/29\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\/","og_locale":"es_ES","og_type":"article","og_title":"Toyota dos millones de unidades fabricadas en su planta de Z\u00e1rate -","og_description":"Toyota celebra un logro excepcional: la producci\u00f3n de dos millones de veh\u00edculos en su planta de Z\u00e1rate, marcando un hito significativo...","og_url":"https:\/\/autofans.com.ar\/index.php\/2023\/12\/29\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\/","article_published_time":"2023-12-29T23:43:36+00:00","og_image":[{"url":"https:\/\/autofans.com.ar\/wp-content\/uploads\/2023\/12\/foto-1-19.jpg","width":640,"height":427,"type":"image\/jpeg"}],"author":"Alejandro Gabriel Rosito","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Alejandro Gabriel Rosito","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/autofans.com.ar\/index.php\/2023\/12\/29\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\/#article","isPartOf":{"@id":"https:\/\/autofans.com.ar\/index.php\/2023\/12\/29\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\/"},"author":{"name":"Alejandro Gabriel Rosito","@id":"https:\/\/autofans.com.ar\/#\/schema\/person\/4a8dda0b6df83ac3d6723e921274c2aa"},"headline":"Toyota dos millones de unidades fabricadas en su planta de Z\u00e1rate","datePublished":"2023-12-29T23:43:36+00:00","mainEntityOfPage":{"@id":"https:\/\/autofans.com.ar\/index.php\/2023\/12\/29\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\/"},"wordCount":432,"image":{"@id":"https:\/\/autofans.com.ar\/index.php\/2023\/12\/29\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\/#primaryimage"},"thumbnailUrl":"https:\/\/autofans.com.ar\/wp-content\/uploads\/2023\/12\/foto-1-19.jpg","keywords":["Dos Millones de Unidades","fabricaci\u00f3n de veh\u00edculos","Hilux","Industria Automotriz","Innovaci\u00f3n automotriz","Pick-up","Producci\u00f3n en Z\u00e1rate","SUV","SW4","Toyota Argentina"],"articleSection":["NOTICIAS","PICK UPs, UTILITARIOS Y OTROS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/autofans.com.ar\/index.php\/2023\/12\/29\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\/","url":"https:\/\/autofans.com.ar\/index.php\/2023\/12\/29\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\/","name":"Toyota dos millones de unidades fabricadas en su planta de Z\u00e1rate -","isPartOf":{"@id":"https:\/\/autofans.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/autofans.com.ar\/index.php\/2023\/12\/29\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\/#primaryimage"},"image":{"@id":"https:\/\/autofans.com.ar\/index.php\/2023\/12\/29\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\/#primaryimage"},"thumbnailUrl":"https:\/\/autofans.com.ar\/wp-content\/uploads\/2023\/12\/foto-1-19.jpg","datePublished":"2023-12-29T23:43:36+00:00","author":{"@id":"https:\/\/autofans.com.ar\/#\/schema\/person\/4a8dda0b6df83ac3d6723e921274c2aa"},"description":"Toyota celebra un logro excepcional: la producci\u00f3n de dos millones de veh\u00edculos en su planta de Z\u00e1rate, marcando un hito significativo...","breadcrumb":{"@id":"https:\/\/autofans.com.ar\/index.php\/2023\/12\/29\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autofans.com.ar\/index.php\/2023\/12\/29\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/autofans.com.ar\/index.php\/2023\/12\/29\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\/#primaryimage","url":"https:\/\/autofans.com.ar\/wp-content\/uploads\/2023\/12\/foto-1-19.jpg","contentUrl":"https:\/\/autofans.com.ar\/wp-content\/uploads\/2023\/12\/foto-1-19.jpg","width":1000,"height":667,"caption":"Toyota"},{"@type":"BreadcrumbList","@id":"https:\/\/autofans.com.ar\/index.php\/2023\/12\/29\/toyota-dos-millones-de-unidades-fabricadas-en-su-planta-de-zarate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/autofans.com.ar\/"},{"@type":"ListItem","position":2,"name":"Toyota dos millones de unidades fabricadas en su planta de Z\u00e1rate"}]},{"@type":"WebSite","@id":"https:\/\/autofans.com.ar\/#website","url":"https:\/\/autofans.com.ar\/","name":"","description":"El multimedio referente de la industria automotriz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autofans.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/autofans.com.ar\/#\/schema\/person\/4a8dda0b6df83ac3d6723e921274c2aa","name":"Alejandro Gabriel Rosito","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/16c5dda1489adfc62618084dcbb91cffd879c374b13fe5dd8e44ed6733852c88?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/16c5dda1489adfc62618084dcbb91cffd879c374b13fe5dd8e44ed6733852c88?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/16c5dda1489adfc62618084dcbb91cffd879c374b13fe5dd8e44ed6733852c88?s=96&d=mm&r=g","caption":"Alejandro Gabriel Rosito"},"url":"https:\/\/autofans.com.ar\/index.php\/author\/gabrielr\/"}]}},"featured_image_urls":{"full":["https:\/\/autofans.com.ar\/wp-content\/uploads\/2023\/12\/foto-1-19.jpg",1000,667,false],"thumbnail":["https:\/\/autofans.com.ar\/wp-content\/uploads\/2023\/12\/foto-1-19-150x150.jpg",150,150,true],"medium":["https:\/\/autofans.com.ar\/wp-content\/uploads\/2023\/12\/foto-1-19-300x200.jpg",300,200,true],"medium_large":["https:\/\/autofans.com.ar\/wp-content\/uploads\/2023\/12\/foto-1-19-768x512.jpg",640,427,true],"large":["https:\/\/autofans.com.ar\/wp-content\/uploads\/2023\/12\/foto-1-19.jpg",640,427,false],"1536x1536":["https:\/\/autofans.com.ar\/wp-content\/uploads\/2023\/12\/foto-1-19.jpg",1000,667,false],"2048x2048":["https:\/\/autofans.com.ar\/wp-content\/uploads\/2023\/12\/foto-1-19.jpg",1000,667,false],"covernews-featured":["https:\/\/autofans.com.ar\/wp-content\/uploads\/2023\/12\/foto-1-19.jpg",1000,667,false],"covernews-medium":["https:\/\/autofans.com.ar\/wp-content\/uploads\/2023\/12\/foto-1-19-540x340.jpg",540,340,true]},"author_info":{"display_name":"Alejandro Gabriel Rosito","author_link":"https:\/\/autofans.com.ar\/index.php\/author\/gabrielr\/"},"category_info":"<a href=\"https:\/\/autofans.com.ar\/index.php\/category\/noticias\/\" rel=\"category tag\">NOTICIAS<\/a> <a href=\"https:\/\/autofans.com.ar\/index.php\/category\/noticias\/otros\/\" rel=\"category tag\">PICK UPs, UTILITARIOS Y OTROS<\/a>","tag_info":"PICK UPs, UTILITARIOS Y OTROS","comment_count":0,"_links":{"self":[{"href":"https:\/\/autofans.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/6157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autofans.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/autofans.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/autofans.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/autofans.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=6157"}],"version-history":[{"count":2,"href":"https:\/\/autofans.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/6157\/revisions"}],"predecessor-version":[{"id":6164,"href":"https:\/\/autofans.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/6157\/revisions\/6164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autofans.com.ar\/index.php\/wp-json\/wp\/v2\/media\/6161"}],"wp:attachment":[{"href":"https:\/\/autofans.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=6157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/autofans.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=6157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/autofans.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=6157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}